{"id":53900,"date":"2024-05-31T14:31:30","date_gmt":"2024-05-31T12:31:30","guid":{"rendered":"https:\/\/www.vmx-service.eu\/product\/bar-pad-maico-tecnosel\/"},"modified":"2025-10-13T17:14:46","modified_gmt":"2025-10-13T15:14:46","slug":"bar-pad-maico-tecnosel","status":"publish","type":"product","link":"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/","title":{"rendered":"Bar pad Maico Tecnosel"},"content":{"rendered":"<p>Gloss red.<\/p>\n<p>Original Tecnosel, made in Italy<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gloss red. Original Tecnosel, made in Italy<\/p>\n","protected":false},"featured_media":39370,"template":"","meta":[],"product_brand":[],"product_cat":[2842,2091],"product_tag":[],"class_list":{"0":"post-53900","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-handlebar-levers-and-parts-en","7":"product_cat-maico-en","8":"entry","9":"has-media","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bar pad Maico Tecnosel - VMX Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bar pad Maico Tecnosel - VMX Service\" \/>\n<meta property=\"og:description\" content=\"Gloss red. Original Tecnosel, made in Italy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/\" \/>\n<meta property=\"og:site_name\" content=\"VMX Service\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T15:14:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2024\/05\/stuur-rol-maico-tecnosel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"264\" \/>\n\t<meta property=\"og:image:height\" content=\"264\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/\",\"url\":\"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/\",\"name\":\"Bar pad Maico Tecnosel - VMX Service\",\"isPartOf\":{\"@id\":\"https:\/\/www.vmx-service.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2024\/05\/stuur-rol-maico-tecnosel.jpg\",\"datePublished\":\"2024-05-31T12:31:30+00:00\",\"dateModified\":\"2025-10-13T15:14:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/#primaryimage\",\"url\":\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2024\/05\/stuur-rol-maico-tecnosel.jpg\",\"contentUrl\":\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2024\/05\/stuur-rol-maico-tecnosel.jpg\",\"width\":264,\"height\":264},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vmx-service.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.vmx-service.eu\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bar pad Maico Tecnosel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vmx-service.eu\/#website\",\"url\":\"https:\/\/www.vmx-service.eu\/\",\"name\":\"VMX Service\",\"description\":\"Vintage MX Parts\",\"publisher\":{\"@id\":\"https:\/\/www.vmx-service.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vmx-service.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vmx-service.eu\/#organization\",\"name\":\"VMX Service\",\"url\":\"https:\/\/www.vmx-service.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.vmx-service.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/01\/VMX-logo.png\",\"contentUrl\":\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/01\/VMX-logo.png\",\"width\":278,\"height\":172,\"caption\":\"VMX Service\"},\"image\":{\"@id\":\"https:\/\/www.vmx-service.eu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bar pad Maico Tecnosel - VMX Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/","og_locale":"en_US","og_type":"article","og_title":"Bar pad Maico Tecnosel - VMX Service","og_description":"Gloss red. Original Tecnosel, made in Italy","og_url":"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/","og_site_name":"VMX Service","article_modified_time":"2025-10-13T15:14:46+00:00","og_image":[{"width":264,"height":264,"url":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2024\/05\/stuur-rol-maico-tecnosel.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/","url":"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/","name":"Bar pad Maico Tecnosel - VMX Service","isPartOf":{"@id":"https:\/\/www.vmx-service.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/#primaryimage"},"image":{"@id":"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2024\/05\/stuur-rol-maico-tecnosel.jpg","datePublished":"2024-05-31T12:31:30+00:00","dateModified":"2025-10-13T15:14:46+00:00","breadcrumb":{"@id":"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/#primaryimage","url":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2024\/05\/stuur-rol-maico-tecnosel.jpg","contentUrl":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2024\/05\/stuur-rol-maico-tecnosel.jpg","width":264,"height":264},{"@type":"BreadcrumbList","@id":"https:\/\/www.vmx-service.eu\/en\/product\/bar-pad-maico-tecnosel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vmx-service.eu\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.vmx-service.eu\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Bar pad Maico Tecnosel"}]},{"@type":"WebSite","@id":"https:\/\/www.vmx-service.eu\/#website","url":"https:\/\/www.vmx-service.eu\/","name":"VMX Service","description":"Vintage MX Parts","publisher":{"@id":"https:\/\/www.vmx-service.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vmx-service.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.vmx-service.eu\/#organization","name":"VMX Service","url":"https:\/\/www.vmx-service.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.vmx-service.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/01\/VMX-logo.png","contentUrl":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/01\/VMX-logo.png","width":278,"height":172,"caption":"VMX Service"},"image":{"@id":"https:\/\/www.vmx-service.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/product\/53900","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/media\/39370"}],"wp:attachment":[{"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/media?parent=53900"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/product_brand?post=53900"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/product_cat?post=53900"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/product_tag?post=53900"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}