{"id":55071,"date":"2025-09-27T18:27:34","date_gmt":"2025-09-27T16:27:34","guid":{"rendered":"https:\/\/www.vmx-service.eu\/product\/carburettor-needle-13383-37f50-n2zh-rm250\/"},"modified":"2025-09-27T18:28:31","modified_gmt":"2025-09-27T16:28:31","slug":"carburettor-needle-13383-37f50-n2zh-rm250","status":"publish","type":"product","link":"https:\/\/www.vmx-service.eu\/en\/product\/carburettor-needle-13383-37f50-n2zh-rm250\/","title":{"rendered":"Carburettor needle 13383-37F50 (N2ZH) RM250"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Carburettor needle, OEM Suzuki in original packing. Number: 13383-37F50<\/p>\n<p>Check the partnumber for fitment. As far as we can tell (but please check yourselves also!!):<\/p>\n<p>2001-2006 Rm250[\/vc_column_text][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Carburettor needle, OEM Suzuki in original packing. Number: 13383-37F50 Check the partnumber for fitment. As far as we can tell (but please check yourselves also!!): 2001-2006 Rm250[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"featured_media":55069,"template":"","meta":[],"product_brand":[],"product_cat":[3357],"product_tag":[],"class_list":{"0":"post-55071","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-carb-parts","7":"entry","8":"has-media","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carburettor needle 13383-37F50 (N2ZH) RM250 - VMX Service<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carburettor needle 13383-37F50 (N2ZH) RM250 - VMX Service\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Carburettor needle, OEM Suzuki in original packing. Number: 13383-37F50 Check the partnumber for fitment. As far as we can tell (but please check yourselves also!!): 2001-2006 Rm250[\/vc_column_text][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/\" \/>\n<meta property=\"og:site_name\" content=\"VMX Service\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-27T16:28:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/09\/13383-37F50.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"806\" \/>\n\t<meta property=\"og:image:height\" content=\"604\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/\",\"url\":\"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/\",\"name\":\"Carburettor needle 13383-37F50 (N2ZH) RM250 - VMX Service\",\"isPartOf\":{\"@id\":\"https:\/\/www.vmx-service.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/09\/13383-37F50.jpg\",\"datePublished\":\"2025-09-27T16:27:34+00:00\",\"dateModified\":\"2025-09-27T16:28:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/#primaryimage\",\"url\":\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/09\/13383-37F50.jpg\",\"contentUrl\":\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/09\/13383-37F50.jpg\",\"width\":806,\"height\":604},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.vmx-service.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.vmx-service.eu\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Carburettor needle 13383-37F50 (N2ZH) RM250\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vmx-service.eu\/#website\",\"url\":\"https:\/\/www.vmx-service.eu\/\",\"name\":\"VMX Service\",\"description\":\"Vintage MX Parts\",\"publisher\":{\"@id\":\"https:\/\/www.vmx-service.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vmx-service.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vmx-service.eu\/#organization\",\"name\":\"VMX Service\",\"url\":\"https:\/\/www.vmx-service.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.vmx-service.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/01\/VMX-logo.png\",\"contentUrl\":\"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/01\/VMX-logo.png\",\"width\":278,\"height\":172,\"caption\":\"VMX Service\"},\"image\":{\"@id\":\"https:\/\/www.vmx-service.eu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carburettor needle 13383-37F50 (N2ZH) RM250 - VMX Service","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/","og_locale":"en_US","og_type":"article","og_title":"Carburettor needle 13383-37F50 (N2ZH) RM250 - VMX Service","og_description":"[vc_row][vc_column][vc_column_text css=&#8221;&#8221;]Carburettor needle, OEM Suzuki in original packing. Number: 13383-37F50 Check the partnumber for fitment. As far as we can tell (but please check yourselves also!!): 2001-2006 Rm250[\/vc_column_text][\/vc_column][\/vc_row]","og_url":"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/","og_site_name":"VMX Service","article_modified_time":"2025-09-27T16:28:31+00:00","og_image":[{"width":806,"height":604,"url":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/09\/13383-37F50.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/","url":"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/","name":"Carburettor needle 13383-37F50 (N2ZH) RM250 - VMX Service","isPartOf":{"@id":"https:\/\/www.vmx-service.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/#primaryimage"},"image":{"@id":"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/09\/13383-37F50.jpg","datePublished":"2025-09-27T16:27:34+00:00","dateModified":"2025-09-27T16:28:31+00:00","breadcrumb":{"@id":"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/#primaryimage","url":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/09\/13383-37F50.jpg","contentUrl":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/09\/13383-37F50.jpg","width":806,"height":604},{"@type":"BreadcrumbList","@id":"https:\/\/www.vmx-service.eu\/product\/gasnaald-13383-37f50-n2zh-rm250\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.vmx-service.eu\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.vmx-service.eu\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Carburettor needle 13383-37F50 (N2ZH) RM250"}]},{"@type":"WebSite","@id":"https:\/\/www.vmx-service.eu\/#website","url":"https:\/\/www.vmx-service.eu\/","name":"VMX Service","description":"Vintage MX Parts","publisher":{"@id":"https:\/\/www.vmx-service.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vmx-service.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.vmx-service.eu\/#organization","name":"VMX Service","url":"https:\/\/www.vmx-service.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.vmx-service.eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/01\/VMX-logo.png","contentUrl":"https:\/\/www.vmx-service.eu\/wp-content\/uploads\/2025\/01\/VMX-logo.png","width":278,"height":172,"caption":"VMX Service"},"image":{"@id":"https:\/\/www.vmx-service.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/product\/55071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/media\/55069"}],"wp:attachment":[{"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/media?parent=55071"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/product_brand?post=55071"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/product_cat?post=55071"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vmx-service.eu\/en\/wp-json\/wp\/v2\/product_tag?post=55071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}